{"id":7541,"date":"2022-01-25T10:42:50","date_gmt":"2022-01-25T10:42:50","guid":{"rendered":"https:\/\/www.cybermedian.com\/es\/?p=7541"},"modified":"2026-04-20T09:13:49","modified_gmt":"2026-04-20T09:13:49","slug":"tecnica-agile-de-priorizacion-de-backlog-moscow","status":"publish","type":"post","link":"https:\/\/www.cybermedian.com\/es\/agile-backlog-prioritization-technique-moscow\/","title":{"rendered":"T\u00e9cnica Agile de Priorizaci\u00f3n de Backlog: MoSCoW"},"content":{"rendered":"<p id=\"60f1\" class=\"graf graf--p graf-after--h3\"><a class=\"markup--anchor markup--p-anchor\" href=\"https:\/\/www.visual-paradigm.com\/scrum\/prioritize-backlog-with-moscow\/\" target=\"_blank\" rel=\"noopener\" data-href=\"https:\/\/www.visual-paradigm.com\/scrum\/prioritize-backlog-with-moscow\/\">MoSCoW es una t\u00e9cnica de priorizaci\u00f3n<\/a>\u00a0\u00a0com\u00fanmente utilizada en Scrum.\u00a0La priorizaci\u00f3n es su capacidad para ver qu\u00e9 tareas y objetivos son m\u00e1s importantes en el momento actual.\u00a0Mientras determina sus prioridades, intente concentrarse en lo que es m\u00e1s importante a expensas de las actividades de menor valor.<\/p>\n<p id=\"1911\" class=\"graf graf--p graf-after--p\">El t\u00e9rmino MoSCoW en s\u00ed mismo es un acr\u00f3nimo derivado de la primera letra de cada una de las cuatro categor\u00edas de priorizaci\u00f3n, como se muestra en la siguiente figura:<\/p>\n<figure id=\"494b\" class=\"graf graf--figure graf-after--p\"><img decoding=\"async\" class=\"graf-image\" src=\"https:\/\/www.cybermedian.com\/es\/wp-content\/uploads\/sites\/8\/2022\/02\/0HKjuVRE7btSmaYFW.png\" data-image-id=\"0*HKjuVRE7btSmaYFW.png\" data-width=\"566\" data-height=\"371\" data-is-featured=\"true\" \/><figcaption class=\"imageCaption\">T\u00e9cnica Agile de Priorizaci\u00f3n de Backlog: MoSCoW<\/figcaption><\/figure>\n<ul class=\"postList\">\n<li id=\"2d9c\" class=\"graf graf--li graf-after--figure\">Debe tener: los requisitos etiquetados como &#8220;DEBEN&#8221; deben incluirse en el cuadro de tiempo de entrega actual para que sea un \u00e9xito.\u00a0Si no se incluye siquiera un requisito &#8220;DEBE&#8221;, la entrega del proyecto debe considerarse un fracaso.<\/li>\n<li id=\"f509\" class=\"graf graf--li graf-after--li\">Deber\u00eda tener: los requisitos &#8220;DEBER\u00cdA&#8221; tambi\u00e9n son cr\u00edticos para el \u00e9xito del proyecto, pero no son necesarios para la entrega en el cuadro de tiempo de entrega actual.<\/li>\n<li id=\"1fde\" class=\"graf graf--li graf-after--li\">Podr\u00eda tener: los requisitos etiquetados como &#8220;PODR\u00cdAN&#8221; son menos cr\u00edticos y, a menudo, se consideran agradables de tener.<\/li>\n<li id=\"4fec\" class=\"graf graf--li graf-after--li\">\u25feNo tendr\u00e1: los requisitos de &#8220;NO&#8221; son los elementos menos cr\u00edticos y de menor recuperaci\u00f3n de la inversi\u00f3n o no son apropiados en ese momento.<\/li>\n<\/ul>\n<p id=\"f269\" class=\"graf graf--p graf-after--li\">MoSCoW se usa a menudo con\u00a0\u00a0<a class=\"markup--anchor markup--p-anchor\" href=\"https:\/\/www.visual-paradigm.com\/scrum\/what-is-time-boxing-in-scrum\/\" target=\"_blank\" rel=\"noopener\" data-href=\"https:\/\/www.visual-paradigm.com\/scrum\/what-is-time-boxing-in-scrum\/\">timeboxing<\/a>\u00a0, donde se fija una fecha l\u00edmite para que el enfoque debe estar en los requisitos m\u00e1s importantes y, como tal, es una t\u00e9cnica com\u00fanmente utilizada en\u00a0 enfoques\u00a0<a class=\"markup--anchor markup--p-anchor\" href=\"https:\/\/www.visual-paradigm.com\/scrum\/what-is-agile-software-development\/\" target=\"_blank\" rel=\"noopener\" data-href=\"https:\/\/www.visual-paradigm.com\/scrum\/what-is-agile-software-development\/\">\u00e1giles de desarrollo de software<\/a>\u00a0\u00a0como\u00a0\u00a0<a class=\"markup--anchor markup--p-anchor\" href=\"https:\/\/www.visual-paradigm.com\/scrum\/scrum-in-3-minutes\/\" target=\"_blank\" rel=\"noopener\" data-href=\"https:\/\/www.visual-paradigm.com\/scrum\/scrum-in-3-minutes\/\">Scrum<\/a>\u00a0\u00a0y DSDM.<\/p>\n<h3 id=\"2058\" class=\"graf graf--h3 graf-after--p\"><span id=\"MoSCoW_Example\">Ejemplo de Mosc\u00fa<\/span><\/h3>\n<p id=\"d448\" class=\"graf graf--p graf-after--h3\">Tomemos un cuerpo humano como un ejemplo hipot\u00e9tico:<\/p>\n<ul class=\"postList\">\n<li id=\"3852\" class=\"graf graf--li graf-after--p\">Debe: un coraz\u00f3n es &#8220;debe&#8221;.\u00a0Sin ella, no hay organismo vivo.\u00a0\u00bfQu\u00e9 es imprescindible en su aplicaci\u00f3n?<\/li>\n<li id=\"54de\" class=\"graf graf--li graf-after--li\">Deber\u00eda: una mano es &#8220;deber\u00eda&#8221;.\u00a0Sin es dificil.\u00a0Pero puedes sobrevivir incluso sin mano.\u00a0Bueno, en la mayor\u00eda de los casos.<\/li>\n<li id=\"3aa4\" class=\"graf graf--li graf-after--li\">Podr\u00eda: el cabello es &#8220;podr\u00eda&#8221;.\u00a0Est\u00e1 bien tenerlos, incluso te ves mejor, pero definitivamente sobrevivir\u00e1s sin ellos.<\/li>\n<li id=\"9e77\" class=\"graf graf--li graf-after--li\">No lo har\u00e1: desperdicio innecesario.\u00a0Por cierto, \u00bfhay algo que &#8220;no&#8221; en un cuerpo?\u00a0(Probablemente, \u00bfpodr\u00eda ser su ap\u00e9ndice?)<\/li>\n<\/ul>\n<h3 id=\"0ac9\" class=\"graf graf--h3 graf-after--li\"><span id=\"Prioritizing_Product_Backlog_Using_MoSCoW_Method\">Priorizaci\u00f3n de la acumulaci\u00f3n de productos mediante el m\u00e9todo MoSCoW<\/span><\/h3>\n<p id=\"f92e\" class=\"graf graf--p graf-after--h3\">El\u00a0\u00a0<a class=\"markup--anchor markup--p-anchor\" href=\"https:\/\/www.visual-paradigm.com\/scrum\/what-is-project-owner-role-in-scrum\/\" target=\"_blank\" rel=\"noopener\" data-href=\"https:\/\/www.visual-paradigm.com\/scrum\/what-is-project-owner-role-in-scrum\/\">propietario del producto<\/a>\u00a0\u00a0es responsable de preparar el\u00a0\u00a0<a class=\"markup--anchor markup--p-anchor\" href=\"https:\/\/www.visual-paradigm.com\/scrum\/what-is-product-backlog-in-scrum\/\" target=\"_blank\" rel=\"noopener\" data-href=\"https:\/\/www.visual-paradigm.com\/scrum\/what-is-product-backlog-in-scrum\/\">Product Backlog<\/a>\u00a0\u00a0y priorizar los elementos en el Product Backlog.\u00a0La priorizaci\u00f3n es uno de los aspectos m\u00e1s importantes de cualquier forma de trabajo de desarrollo porque elegir lo correcto le permite maximizar el valor entregado en un\u00a0\u00a0<a class=\"markup--anchor markup--p-anchor\" href=\"https:\/\/www.visual-paradigm.com\/scrum\/what-is-sprint-in-scrum\/\" target=\"_blank\" rel=\"noopener\" data-href=\"https:\/\/www.visual-paradigm.com\/scrum\/what-is-sprint-in-scrum\/\">Sprint<\/a>\u00a0.\u00a0Los elementos del Product Backlog deben ordenarse de tal manera que los requisitos con el m\u00e1ximo valor comercial se completen primero y faculten a un equipo para moverse en una direcci\u00f3n uniforme hacia un objetivo com\u00fan.<\/p>\n<figure id=\"d705\" class=\"graf graf--figure graf-after--p\"><img decoding=\"async\" class=\"graf-image\" src=\"https:\/\/www.cybermedian.com\/es\/wp-content\/uploads\/sites\/8\/2022\/02\/0G7eSTXzv35X2W-sM.png\" data-image-id=\"0*G7eSTXzv35X2W-sM.png\" data-width=\"658\" data-height=\"424\" \/><figcaption class=\"imageCaption\">Priorizaci\u00f3n de la acumulaci\u00f3n de productos mediante el m\u00e9todo MoSCoW<\/figcaption><\/figure>\n<h3 id=\"9d36\" class=\"graf graf--h3 graf-after--figure\"><span id=\"Prioritization_Criteria\">Criterios de priorizaci\u00f3n<\/span><\/h3>\n<p id=\"f6d2\" class=\"graf graf--p graf-after--h3\">Al realizar la priorizaci\u00f3n de los elementos de la cartera de productos en la\u00a0 sesi\u00f3n\u00a0<a class=\"markup--anchor markup--p-anchor\" href=\"https:\/\/www.visual-paradigm.com\/scrum\/what-is-sprint-planning\/\" target=\"_blank\" rel=\"noopener\" data-href=\"https:\/\/www.visual-paradigm.com\/scrum\/what-is-sprint-planning\/\">de planificaci\u00f3n de Sprint<\/a>\u00a0\u00a0, aqu\u00ed hay una lista de criterios a considerar para sus decisiones.<\/p>\n<ul class=\"postList\">\n<li id=\"bbe6\" class=\"graf graf--li graf-after--p\">Alto valor para el cliente<\/li>\n<li id=\"106a\" class=\"graf graf--li graf-after--li\">Alto beneficio para el negocio.<\/li>\n<li id=\"602e\" class=\"graf graf--li graf-after--li\">F\u00e1cil de implementar<\/li>\n<li id=\"4cd8\" class=\"graf graf--li graf-after--li\">Alto riesgo<\/li>\n<li id=\"a04e\" class=\"graf graf--li graf-after--li\">Alto costo si no se implementa lo antes posible<\/li>\n<li id=\"34af\" class=\"graf graf--li graf-after--li\">Dependencias entre elementos<\/li>\n<li id=\"bb52\" class=\"graf graf--li graf-after--li\">\u00bf Contribuir m\u00e1s a la pr\u00f3xima\u00a0\u00a0<a class=\"markup--anchor markup--li-anchor\" href=\"https:\/\/www.visual-paradigm.com\/scrum\/write-sprint-goal\/\" target=\"_blank\" rel=\"noopener\" data-href=\"https:\/\/www.visual-paradigm.com\/scrum\/write-sprint-goal\/\">meta de Sprint<\/a>\u00a0?<\/li>\n<\/ul>\n<p id=\"af4f\" class=\"graf graf--p graf-after--li graf--trailing\"><a class=\"markup--anchor markup--p-anchor\" href=\"https:\/\/www.visual-paradigm.com\/scrum\/\" target=\"_blank\" rel=\"nofollow noopener\" data-href=\"https:\/\/www.visual-paradigm.com\/scrum\/\">Art\u00edculos recomendados de Agile y Scrum<\/a><\/p>\n<div class=\"infoart-templates-item\">\n<p><a href=\"https:\/\/online.visual-paradigm.com\/diagrams\/templates\/moscow-method\/moscow-prioritization-and-scoping\/\"><img decoding=\"async\" id=\"moscow-prioritization-and-scoping\" class=\"related-templates-masonry-content lozad\" title=\"Priorizaci\u00f3n y alcance de Mosc\u00fa\" src=\"https:\/\/www.cybermedian.com\/es\/wp-content\/uploads\/sites\/8\/2022\/02\/moscow-prioritization-and-scoping.png\" alt=\"Plantilla del m\u00e9todo MOSCOW: priorizaci\u00f3n y alcance de MoSCoW (creado por el creador del m\u00e9todo MOSCOW de Diagrams)\" data-src=\"https:\/\/www.cybermedian.com\/es\/wp-content\/uploads\/sites\/8\/2022\/02\/moscow-prioritization-and-scoping.png\" data-loaded=\"true\" \/><\/a><\/p>\n<div class=\"template-caption-front\" title=\"Priorizaci\u00f3n y alcance de Mosc\u00fa\"><a href=\"https:\/\/online.visual-paradigm.com\/app\/diagrams\/#diagram:proj=0&amp;type=MoSCoWMethod&amp;gallery=\/repository\/0815440b-5b5d-423d-bb61-9d965ce309f9.xml&amp;name=MoSCoW%20Prioritization%20and%20Scoping\" target=\"_blank\" rel=\"noopener\"><span class=\"caption-box\">Priorizaci\u00f3n y alcance de Mosc\u00fa<\/span><\/a><\/div>\n<\/div>\n<div class=\"infoart-templates-item\">\n<p><a href=\"https:\/\/online.visual-paradigm.com\/diagrams\/templates\/moscow-method\/moscow-prioritization-template\/\"><img decoding=\"async\" id=\"moscow-prioritization-template\" class=\"related-templates-masonry-content lozad\" title=\"Plantilla de priorizaci\u00f3n de Mosc\u00fa\" src=\"https:\/\/www.cybermedian.com\/es\/wp-content\/uploads\/sites\/8\/2022\/02\/moscow-prioritization-template.png\" alt=\"Plantilla del m\u00e9todo MOSC\u00da: plantilla de priorizaci\u00f3n de MoSCoW (creada por el creador del m\u00e9todo MOSC\u00da de Diagrams)\" data-src=\"https:\/\/www.cybermedian.com\/es\/wp-content\/uploads\/sites\/8\/2022\/02\/moscow-prioritization-template.png\" data-loaded=\"true\" \/><\/a><\/p>\n<div class=\"template-caption-front\" title=\"Plantilla de priorizaci\u00f3n de Mosc\u00fa\"><a href=\"https:\/\/online.visual-paradigm.com\/app\/diagrams\/#diagram:proj=0&amp;type=MoSCoWMethod&amp;gallery=\/repository\/16fef711-2669-4444-9320-5abe23b3acd8.xml&amp;name=MoSCoW%20Prioritization%20Template\" target=\"_blank\" rel=\"noopener\"><span class=\"caption-box\">Plantilla de priorizaci\u00f3n de Mosc\u00fa<\/span><\/a><\/div>\n<\/div>\n<div class=\"infoart-templates-item\">\n<p><a href=\"https:\/\/online.visual-paradigm.com\/diagrams\/templates\/moscow-method\/moscow-template\/\"><img decoding=\"async\" id=\"moscow-template\" class=\"related-templates-masonry-content lozad\" title=\"Plantilla de Mosc\u00fa\" src=\"https:\/\/www.cybermedian.com\/es\/wp-content\/uploads\/sites\/8\/2022\/02\/moscow-template.png\" alt=\"Plantilla del M\u00e9todo MOSC\u00da: Plantilla MoSCoW (Creada por el fabricante del M\u00e9todo MOSC\u00da de Diagrams)\" data-src=\"https:\/\/www.cybermedian.com\/es\/wp-content\/uploads\/sites\/8\/2022\/02\/moscow-template.png\" data-loaded=\"true\" \/><\/a><\/p>\n<div class=\"template-caption-front\" title=\"Plantilla de Mosc\u00fa\"><a href=\"https:\/\/online.visual-paradigm.com\/app\/diagrams\/#diagram:proj=0&amp;type=MoSCoWMethod&amp;gallery=\/repository\/680516a1-f243-4419-ba9b-5881e9bc6e8f.xml&amp;name=MoSCoW%20Template\" target=\"_blank\" rel=\"noopener\"><span class=\"caption-box\">Plantilla de Mosc\u00fa<\/span><\/a><\/div>\n<\/div>\n<div class=\"infoart-templates-item\">\n<p><a href=\"https:\/\/online.visual-paradigm.com\/diagrams\/templates\/moscow-method\/moscow-method-template\/\"><img decoding=\"async\" id=\"moscow-method-template\" class=\"related-templates-masonry-content lozad\" title=\"Plantilla del m\u00e9todo de Mosc\u00fa\" src=\"https:\/\/www.cybermedian.com\/es\/wp-content\/uploads\/sites\/8\/2022\/02\/moscow-method-template.png\" alt=\"Plantilla del m\u00e9todo MOSC\u00da: Plantilla del m\u00e9todo MoSCoW (creada por el creador del m\u00e9todo MOSC\u00da de Diagrams)\" data-src=\"https:\/\/www.cybermedian.com\/es\/wp-content\/uploads\/sites\/8\/2022\/02\/moscow-method-template.png\" data-loaded=\"true\" \/><\/a><\/p>\n<div class=\"template-caption-front\" title=\"Plantilla del m\u00e9todo de Mosc\u00fa\"><a href=\"https:\/\/online.visual-paradigm.com\/app\/diagrams\/#diagram:proj=0&amp;type=MoSCoWMethod&amp;gallery=\/repository\/94ea42d6-5946-4be9-b16d-338f5f5640f7.xml&amp;name=MoSCoW%20Method%20Template\" target=\"_blank\" rel=\"noopener\"><span class=\"caption-box\">Plantilla del m\u00e9todo de Mosc\u00fa<\/span><\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El m\u00e9todo MoSCoW permite clasificar las necesidades de los usuarios en funci\u00f3n de su prioridad. Ayuda a desarrollar una clara comprensi\u00f3n de los requisitos de los clientes y su prioridad. MoSCoW significa must, should, could y would. Visual Paradigm viene con un rico conjunto de plantillas de diagramas. Puede empezar con un diagrama en blanco o con una plantilla de M\u00e9todo MoSCoW ya hecha.<\/p>\n","protected":false},"author":3,"featured_media":7545,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_wpseo_title":"","_yoast_wpseo_metadesc":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-7541","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agile-project-management"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>T\u00e9cnica Agile de Priorizaci\u00f3n de Backlog: MoSCoW - Cibermedio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cybermedian.com\/es\/agile-backlog-prioritization-technique-moscow\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T\u00e9cnica Agile de Priorizaci\u00f3n de Backlog: MoSCoW - Cibermedio\" \/>\n<meta property=\"og:description\" content=\"El m\u00e9todo MoSCoW permite clasificar las necesidades de los usuarios en funci\u00f3n de su prioridad. Ayuda a desarrollar una clara comprensi\u00f3n de los requisitos de los clientes y su prioridad. MoSCoW significa must, should, could y would. Visual Paradigm viene con un rico conjunto de plantillas de diagramas. Puede empezar con un diagrama en blanco o con una plantilla de M\u00e9todo MoSCoW ya hecha.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cybermedian.com\/es\/agile-backlog-prioritization-technique-moscow\/\" \/>\n<meta property=\"og:site_name\" content=\"Cibermedio\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-25T10:42:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-20T09:13:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn-images.visual-paradigm.com\/features\/v16\/2\/moscow-method-tool\/moscow-method-tool.png\" \/>\n<meta name=\"author\" content=\"vpvera\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cdn-images.visual-paradigm.com\/features\/v16\/2\/moscow-method-tool\/moscow-method-tool.png\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"vpvera\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.cybermedian.com\/es\/agile-backlog-prioritization-technique-moscow\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.cybermedian.com\/es\/agile-backlog-prioritization-technique-moscow\/\"},\"author\":{\"name\":\"vpvera\",\"@id\":\"https:\/\/www.cybermedian.com\/es\/#\/schema\/person\/54a5a46528997d1917d55add9b0de7d5\"},\"headline\":\"T\u00e9cnica Agile de Priorizaci\u00f3n de Backlog: MoSCoW\",\"datePublished\":\"2022-01-25T10:42:50+00:00\",\"dateModified\":\"2026-04-20T09:13:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.cybermedian.com\/es\/agile-backlog-prioritization-technique-moscow\/\"},\"wordCount\":586,\"commentCount\":3,\"image\":{\"@id\":\"https:\/\/www.cybermedian.com\/es\/agile-backlog-prioritization-technique-moscow\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cdn-images.visual-paradigm.com\/features\/v16\/2\/moscow-method-tool\/moscow-method-tool.png\",\"articleSection\":[\"Agile Project Management\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.cybermedian.com\/es\/agile-backlog-prioritization-technique-moscow\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cybermedian.com\/es\/agile-backlog-prioritization-technique-moscow\/\",\"url\":\"https:\/\/www.cybermedian.com\/es\/agile-backlog-prioritization-technique-moscow\/\",\"name\":\"T\u00e9cnica Agile de Priorizaci\u00f3n de Backlog: MoSCoW - Cibermedio\",\"isPartOf\":{\"@id\":\"https:\/\/www.cybermedian.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.cybermedian.com\/es\/agile-backlog-prioritization-technique-moscow\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.cybermedian.com\/es\/agile-backlog-prioritization-technique-moscow\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cdn-images.visual-paradigm.com\/features\/v16\/2\/moscow-method-tool\/moscow-method-tool.png\",\"datePublished\":\"2022-01-25T10:42:50+00:00\",\"dateModified\":\"2026-04-20T09:13:49+00:00\",\"author\":{\"@id\":\"https:\/\/www.cybermedian.com\/es\/#\/schema\/person\/54a5a46528997d1917d55add9b0de7d5\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.cybermedian.com\/es\/agile-backlog-prioritization-technique-moscow\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cybermedian.com\/es\/agile-backlog-prioritization-technique-moscow\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cybermedian.com\/es\/agile-backlog-prioritization-technique-moscow\/#primaryimage\",\"url\":\"https:\/\/cdn-images.visual-paradigm.com\/features\/v16\/2\/moscow-method-tool\/moscow-method-tool.png\",\"contentUrl\":\"https:\/\/cdn-images.visual-paradigm.com\/features\/v16\/2\/moscow-method-tool\/moscow-method-tool.png\",\"width\":\"1170\",\"height\":\"658\",\"caption\":\"T\u00e9cnica Agile de Priorizaci\u00f3n de Backlog: MoSCoW\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cybermedian.com\/es\/agile-backlog-prioritization-technique-moscow\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.cybermedian.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T\u00e9cnica Agile de Priorizaci\u00f3n de Backlog: MoSCoW\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cybermedian.com\/es\/#website\",\"url\":\"https:\/\/www.cybermedian.com\/es\/\",\"name\":\"Cibermedio\",\"description\":\"Aprendiendo una cosa nueva todos los d\u00edas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cybermedian.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cybermedian.com\/es\/#\/schema\/person\/54a5a46528997d1917d55add9b0de7d5\",\"name\":\"vpvera\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cybermedian.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/308f3b229618b77cd1764bf92dc496296ea49a0db7c1c881fa7c4f063b2b58da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/308f3b229618b77cd1764bf92dc496296ea49a0db7c1c881fa7c4f063b2b58da?s=96&d=mm&r=g\",\"caption\":\"vpvera\"},\"url\":\"https:\/\/www.cybermedian.com\/es\/author\/vpvera\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00e9cnica Agile de Priorizaci\u00f3n de Backlog: MoSCoW - Cibermedio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cybermedian.com\/es\/agile-backlog-prioritization-technique-moscow\/","og_locale":"es_ES","og_type":"article","og_title":"T\u00e9cnica Agile de Priorizaci\u00f3n de Backlog: MoSCoW - Cibermedio","og_description":"El m\u00e9todo MoSCoW permite clasificar las necesidades de los usuarios en funci\u00f3n de su prioridad. Ayuda a desarrollar una clara comprensi\u00f3n de los requisitos de los clientes y su prioridad. MoSCoW significa must, should, could y would. Visual Paradigm viene con un rico conjunto de plantillas de diagramas. Puede empezar con un diagrama en blanco o con una plantilla de M\u00e9todo MoSCoW ya hecha.","og_url":"https:\/\/www.cybermedian.com\/es\/agile-backlog-prioritization-technique-moscow\/","og_site_name":"Cibermedio","article_published_time":"2022-01-25T10:42:50+00:00","article_modified_time":"2026-04-20T09:13:49+00:00","og_image":[{"url":"https:\/\/cdn-images.visual-paradigm.com\/features\/v16\/2\/moscow-method-tool\/moscow-method-tool.png","type":"","width":"","height":""}],"author":"vpvera","twitter_card":"summary_large_image","twitter_image":"https:\/\/cdn-images.visual-paradigm.com\/features\/v16\/2\/moscow-method-tool\/moscow-method-tool.png","twitter_misc":{"Escrito por":"vpvera","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cybermedian.com\/es\/agile-backlog-prioritization-technique-moscow\/#article","isPartOf":{"@id":"https:\/\/www.cybermedian.com\/es\/agile-backlog-prioritization-technique-moscow\/"},"author":{"name":"vpvera","@id":"https:\/\/www.cybermedian.com\/es\/#\/schema\/person\/54a5a46528997d1917d55add9b0de7d5"},"headline":"T\u00e9cnica Agile de Priorizaci\u00f3n de Backlog: MoSCoW","datePublished":"2022-01-25T10:42:50+00:00","dateModified":"2026-04-20T09:13:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cybermedian.com\/es\/agile-backlog-prioritization-technique-moscow\/"},"wordCount":586,"commentCount":3,"image":{"@id":"https:\/\/www.cybermedian.com\/es\/agile-backlog-prioritization-technique-moscow\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn-images.visual-paradigm.com\/features\/v16\/2\/moscow-method-tool\/moscow-method-tool.png","articleSection":["Agile Project Management"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cybermedian.com\/es\/agile-backlog-prioritization-technique-moscow\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cybermedian.com\/es\/agile-backlog-prioritization-technique-moscow\/","url":"https:\/\/www.cybermedian.com\/es\/agile-backlog-prioritization-technique-moscow\/","name":"T\u00e9cnica Agile de Priorizaci\u00f3n de Backlog: MoSCoW - Cibermedio","isPartOf":{"@id":"https:\/\/www.cybermedian.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cybermedian.com\/es\/agile-backlog-prioritization-technique-moscow\/#primaryimage"},"image":{"@id":"https:\/\/www.cybermedian.com\/es\/agile-backlog-prioritization-technique-moscow\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn-images.visual-paradigm.com\/features\/v16\/2\/moscow-method-tool\/moscow-method-tool.png","datePublished":"2022-01-25T10:42:50+00:00","dateModified":"2026-04-20T09:13:49+00:00","author":{"@id":"https:\/\/www.cybermedian.com\/es\/#\/schema\/person\/54a5a46528997d1917d55add9b0de7d5"},"breadcrumb":{"@id":"https:\/\/www.cybermedian.com\/es\/agile-backlog-prioritization-technique-moscow\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cybermedian.com\/es\/agile-backlog-prioritization-technique-moscow\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cybermedian.com\/es\/agile-backlog-prioritization-technique-moscow\/#primaryimage","url":"https:\/\/cdn-images.visual-paradigm.com\/features\/v16\/2\/moscow-method-tool\/moscow-method-tool.png","contentUrl":"https:\/\/cdn-images.visual-paradigm.com\/features\/v16\/2\/moscow-method-tool\/moscow-method-tool.png","width":"1170","height":"658","caption":"T\u00e9cnica Agile de Priorizaci\u00f3n de Backlog: MoSCoW"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cybermedian.com\/es\/agile-backlog-prioritization-technique-moscow\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cybermedian.com\/es\/"},{"@type":"ListItem","position":2,"name":"T\u00e9cnica Agile de Priorizaci\u00f3n de Backlog: MoSCoW"}]},{"@type":"WebSite","@id":"https:\/\/www.cybermedian.com\/es\/#website","url":"https:\/\/www.cybermedian.com\/es\/","name":"Cibermedio","description":"Aprendiendo una cosa nueva todos los d\u00edas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cybermedian.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.cybermedian.com\/es\/#\/schema\/person\/54a5a46528997d1917d55add9b0de7d5","name":"vpvera","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cybermedian.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/308f3b229618b77cd1764bf92dc496296ea49a0db7c1c881fa7c4f063b2b58da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/308f3b229618b77cd1764bf92dc496296ea49a0db7c1c881fa7c4f063b2b58da?s=96&d=mm&r=g","caption":"vpvera"},"url":"https:\/\/www.cybermedian.com\/es\/author\/vpvera\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cybermedian.com\/es\/wp-json\/wp\/v2\/posts\/7541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cybermedian.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cybermedian.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cybermedian.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cybermedian.com\/es\/wp-json\/wp\/v2\/comments?post=7541"}],"version-history":[{"count":3,"href":"https:\/\/www.cybermedian.com\/es\/wp-json\/wp\/v2\/posts\/7541\/revisions"}],"predecessor-version":[{"id":7544,"href":"https:\/\/www.cybermedian.com\/es\/wp-json\/wp\/v2\/posts\/7541\/revisions\/7544"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cybermedian.com\/es\/wp-json\/wp\/v2\/media\/7545"}],"wp:attachment":[{"href":"https:\/\/www.cybermedian.com\/es\/wp-json\/wp\/v2\/media?parent=7541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cybermedian.com\/es\/wp-json\/wp\/v2\/categories?post=7541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cybermedian.com\/es\/wp-json\/wp\/v2\/tags?post=7541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}